{"id":781,"date":"2021-12-08T20:06:42","date_gmt":"2021-12-08T19:06:42","guid":{"rendered":"https:\/\/www.albokaabesbatza.com\/?p=781"},"modified":"2022-05-23T17:28:46","modified_gmt":"2022-05-23T15:28:46","slug":"concierto-de-navidad","status":"publish","type":"post","link":"https:\/\/www.albokaabesbatza.com\/eu\/concierto-de-navidad\/","title":{"rendered":"GABONAKO KONTZERTUA &#8211; ABENDUAK 18"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":782,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-781","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.albokaabesbatza.com\/eu\/wp-json\/wp\/v2\/posts\/781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albokaabesbatza.com\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albokaabesbatza.com\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albokaabesbatza.com\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albokaabesbatza.com\/eu\/wp-json\/wp\/v2\/comments?post=781"}],"version-history":[{"count":8,"href":"https:\/\/www.albokaabesbatza.com\/eu\/wp-json\/wp\/v2\/posts\/781\/revisions"}],"predecessor-version":[{"id":801,"href":"https:\/\/www.albokaabesbatza.com\/eu\/wp-json\/wp\/v2\/posts\/781\/revisions\/801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albokaabesbatza.com\/eu\/wp-json\/wp\/v2\/media\/782"}],"wp:attachment":[{"href":"https:\/\/www.albokaabesbatza.com\/eu\/wp-json\/wp\/v2\/media?parent=781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albokaabesbatza.com\/eu\/wp-json\/wp\/v2\/categories?post=781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albokaabesbatza.com\/eu\/wp-json\/wp\/v2\/tags?post=781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}